{"id":28948,"date":"2018-03-26T12:15:00","date_gmt":"2018-03-26T09:15:00","guid":{"rendered":"https:\/\/www.plmf.ee\/venue\/otepaa-culture-center-2\/"},"modified":"2018-03-26T12:15:00","modified_gmt":"2018-03-26T09:15:00","slug":"otepaa-culture-center-2","status":"publish","type":"tribe_venue","link":"https:\/\/plmf.ee\/en\/venue\/otepaa-culture-center-2\/","title":{"rendered":"Otep\u00e4\u00e4 Culture Center"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":0,"template":"","meta":{"footnotes":""},"class_list":["post-28948","tribe_venue","type-tribe_venue","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Otep\u00e4\u00e4 Culture Center - Pille Lill Music Fund<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.plmf.ee\/en\/venue\/otepaa-culture-center-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Otep\u00e4\u00e4 Culture Center - Pille Lill Music Fund\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.plmf.ee\/en\/venue\/otepaa-culture-center-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Pille Lill Music Fund\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.plmf.ee\/en\/venue\/otepaa-culture-center-2\/\",\"url\":\"https:\/\/www.plmf.ee\/en\/venue\/otepaa-culture-center-2\/\",\"name\":\"Otep\u00e4\u00e4 Culture Center - Pille Lill Music Fund\",\"isPartOf\":{\"@id\":\"https:\/\/plmf.ee\/en\/#website\"},\"datePublished\":\"2018-03-26T09:15:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.plmf.ee\/en\/venue\/otepaa-culture-center-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.plmf.ee\/en\/venue\/otepaa-culture-center-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.plmf.ee\/en\/venue\/otepaa-culture-center-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/plmf.ee\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Otep\u00e4\u00e4 Culture Center\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/plmf.ee\/en\/#website\",\"url\":\"https:\/\/plmf.ee\/en\/\",\"name\":\"Pille Lill Music Fund\",\"description\":\"Planet Of Talent\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/plmf.ee\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Otep\u00e4\u00e4 Culture Center - Pille Lill Music Fund","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.plmf.ee\/en\/venue\/otepaa-culture-center-2\/","og_locale":"en_US","og_type":"article","og_title":"Otep\u00e4\u00e4 Culture Center - Pille Lill Music Fund","og_url":"https:\/\/www.plmf.ee\/en\/venue\/otepaa-culture-center-2\/","og_site_name":"Pille Lill Music Fund","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.plmf.ee\/en\/venue\/otepaa-culture-center-2\/","url":"https:\/\/www.plmf.ee\/en\/venue\/otepaa-culture-center-2\/","name":"Otep\u00e4\u00e4 Culture Center - Pille Lill Music Fund","isPartOf":{"@id":"https:\/\/plmf.ee\/en\/#website"},"datePublished":"2018-03-26T09:15:00+00:00","breadcrumb":{"@id":"https:\/\/www.plmf.ee\/en\/venue\/otepaa-culture-center-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.plmf.ee\/en\/venue\/otepaa-culture-center-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.plmf.ee\/en\/venue\/otepaa-culture-center-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/plmf.ee\/en\/"},{"@type":"ListItem","position":2,"name":"Otep\u00e4\u00e4 Culture Center"}]},{"@type":"WebSite","@id":"https:\/\/plmf.ee\/en\/#website","url":"https:\/\/plmf.ee\/en\/","name":"Pille Lill Music Fund","description":"Planet Of Talent","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/plmf.ee\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/plmf.ee\/en\/wp-json\/wp\/v2\/tribe_venue\/28948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plmf.ee\/en\/wp-json\/wp\/v2\/tribe_venue"}],"about":[{"href":"https:\/\/plmf.ee\/en\/wp-json\/wp\/v2\/types\/tribe_venue"}],"author":[{"embeddable":true,"href":"https:\/\/plmf.ee\/en\/wp-json\/wp\/v2\/users\/7"}],"version-history":[{"count":0,"href":"https:\/\/plmf.ee\/en\/wp-json\/wp\/v2\/tribe_venue\/28948\/revisions"}],"wp:attachment":[{"href":"https:\/\/plmf.ee\/en\/wp-json\/wp\/v2\/media?parent=28948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}